{"id":217,"count":1,"description":"","link":"http:\/\/dhoytt.com\/mainblog\/tag\/flexibility\/","name":"Flexibility","slug":"flexibility","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/dhoytt.com\/mainblog\/wp-json\/wp\/v2\/tags\/217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/dhoytt.com\/mainblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/dhoytt.com\/mainblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/dhoytt.com\/mainblog\/wp-json\/wp\/v2\/posts?tags=217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}